{"id":15,"count":6,"description":"","link":"https:\/\/jnews.jegstudio.com\/anglingnews\/category\/contest\/","name":"Contest","slug":"contest","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/jnews.jegstudio.com\/anglingnews\/wp-json\/wp\/v2\/categories\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jnews.jegstudio.com\/anglingnews\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/jnews.jegstudio.com\/anglingnews\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/jnews.jegstudio.com\/anglingnews\/wp-json\/wp\/v2\/posts?categories=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}