{"id":3,"count":13,"description":"","link":"https:\/\/jnews.jegstudio.com\/bloomnews\/category\/entertainment\/","name":"Entertainment","slug":"entertainment","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/jnews.jegstudio.com\/bloomnews\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jnews.jegstudio.com\/bloomnews\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/jnews.jegstudio.com\/bloomnews\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/jnews.jegstudio.com\/bloomnews\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}