{"id":14,"count":10,"description":"A wonderful serenity has taken possession of my entire soul, like these sweet mornings of spring which I enjoy with my whole heart.","link":"https:\/\/jnews.jegstudio.com\/business\/category\/tech\/gadget\/","name":"Gadget","slug":"gadget","taxonomy":"category","parent":12,"meta":[],"_links":{"self":[{"href":"https:\/\/jnews.jegstudio.com\/business\/wp-json\/wp\/v2\/categories\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jnews.jegstudio.com\/business\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/jnews.jegstudio.com\/business\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/jnews.jegstudio.com\/business\/wp-json\/wp\/v2\/categories\/12"}],"wp:post_type":[{"href":"https:\/\/jnews.jegstudio.com\/business\/wp-json\/wp\/v2\/posts?categories=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}