{"id":16,"count":14,"description":"You can add some category description here.","link":"https:\/\/jnews.jegstudio.com\/localnews\/category\/opinion\/","name":"Opinion","slug":"opinion","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/jnews.jegstudio.com\/localnews\/wp-json\/wp\/v2\/categories\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jnews.jegstudio.com\/localnews\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/jnews.jegstudio.com\/localnews\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/jnews.jegstudio.com\/localnews\/wp-json\/wp\/v2\/posts?categories=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}