{"id":14,"count":7,"description":"Lorem ipsum dolor amet photo booth iceland cliche, subway tile single-origin coffee live-edge poutine man braid fanny pack keffiyeh squid pabst flannel irony.","link":"https:\/\/jnews.jegstudio.com\/metro\/category\/news\/politics\/","name":"Politics","slug":"politics","taxonomy":"category","parent":12,"meta":[],"_links":{"self":[{"href":"https:\/\/jnews.jegstudio.com\/metro\/wp-json\/wp\/v2\/categories\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jnews.jegstudio.com\/metro\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/jnews.jegstudio.com\/metro\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/jnews.jegstudio.com\/metro\/wp-json\/wp\/v2\/categories\/12"}],"wp:post_type":[{"href":"https:\/\/jnews.jegstudio.com\/metro\/wp-json\/wp\/v2\/posts?categories=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}