{"id":111,"count":1,"description":"","link":"https:\/\/jnews.jegstudio.com\/metro\/tag\/learned\/","name":"Learned","slug":"learned","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/jnews.jegstudio.com\/metro\/wp-json\/wp\/v2\/tags\/111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jnews.jegstudio.com\/metro\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jnews.jegstudio.com\/metro\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jnews.jegstudio.com\/metro\/wp-json\/wp\/v2\/posts?tags=111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}