{"id":197,"count":1,"description":"","link":"https:\/\/jnews.jegstudio.com\/metro\/tag\/published\/","name":"Published","slug":"published","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/jnews.jegstudio.com\/metro\/wp-json\/wp\/v2\/tags\/197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jnews.jegstudio.com\/metro\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jnews.jegstudio.com\/metro\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jnews.jegstudio.com\/metro\/wp-json\/wp\/v2\/posts?tags=197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}