{"id":18,"count":22,"description":"A wonderful serenity has taken possession of my entire soul, like these sweet mornings of spring which I enjoy with my whole heart.","link":"https:\/\/jnews.jegstudio.com\/movie\/category\/genre\/action\/","name":"Action","slug":"action","taxonomy":"category","parent":17,"meta":[],"_links":{"self":[{"href":"https:\/\/jnews.jegstudio.com\/movie\/wp-json\/wp\/v2\/categories\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jnews.jegstudio.com\/movie\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/jnews.jegstudio.com\/movie\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/jnews.jegstudio.com\/movie\/wp-json\/wp\/v2\/categories\/17"}],"wp:post_type":[{"href":"https:\/\/jnews.jegstudio.com\/movie\/wp-json\/wp\/v2\/posts?categories=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}