{"id":2,"count":6,"description":"","link":"https:\/\/jnews.jegstudio.com\/pets\/category\/wellness\/","name":"Wellness","slug":"wellness","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/jnews.jegstudio.com\/pets\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jnews.jegstudio.com\/pets\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/jnews.jegstudio.com\/pets\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/jnews.jegstudio.com\/pets\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}