{"id":48,"count":8,"description":"A small river named Duden flows by their place and supplies it with the necessary regelialia. It is a paradisematic country, in which roasted parts of sentences fly into your mouth.","link":"https:\/\/jnews.jegstudio.com\/podcast\/series\/our-time-podcast\/","name":"Our Time Podcast","slug":"our-time-podcast","taxonomy":"jnews-series","meta":[],"_links":{"self":[{"href":"https:\/\/jnews.jegstudio.com\/podcast\/wp-json\/wp\/v2\/jnews-series\/48","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jnews.jegstudio.com\/podcast\/wp-json\/wp\/v2\/jnews-series"}],"about":[{"href":"https:\/\/jnews.jegstudio.com\/podcast\/wp-json\/wp\/v2\/taxonomies\/jnews-series"}],"wp:post_type":[{"href":"https:\/\/jnews.jegstudio.com\/podcast\/wp-json\/wp\/v2\/posts?jnews-series=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}