{"id":6,"count":16,"description":"","link":"https:\/\/jnews.jegstudio.com\/relationships\/category\/friendship\/","name":"Friendship","slug":"friendship","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/jnews.jegstudio.com\/relationships\/wp-json\/wp\/v2\/categories\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jnews.jegstudio.com\/relationships\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/jnews.jegstudio.com\/relationships\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/jnews.jegstudio.com\/relationships\/wp-json\/wp\/v2\/posts?categories=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}