{"id":46,"count":13,"description":"You can change the description on each category from the WordPress administration panel.","link":"https:\/\/jnews.jegstudio.com\/reportase\/category\/science\/","name":"Science","slug":"science","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/jnews.jegstudio.com\/reportase\/wp-json\/wp\/v2\/categories\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jnews.jegstudio.com\/reportase\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/jnews.jegstudio.com\/reportase\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/jnews.jegstudio.com\/reportase\/wp-json\/wp\/v2\/posts?categories=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}